{"id":787,"date":"2023-02-25T11:47:17","date_gmt":"2023-02-25T14:47:17","guid":{"rendered":"https:\/\/padregraziano.com\/?p=787"},"modified":"2023-02-25T11:47:19","modified_gmt":"2023-02-25T14:47:19","slug":"1o-domingo-da-quaresma","status":"publish","type":"post","link":"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/","title":{"rendered":"<strong>A coragem de olhar dentro de n\u00f3s<\/strong>"},"content":{"rendered":"\n<p><strong>Homilia do 1\u00ba Domingo da Quaresma \u2013 Ano A<\/strong><\/p>\n\n\n\n<p><strong>(15\/03\/2011)<\/strong><\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>Leituras:<\/strong><\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\">Gn 2,7-9.3,1-7<\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\">Sl 50(51),3-4.5-6a.12-13.14.17 (R. cf. 3a) ou ou mais breve 5,12.17-19<\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\">Rm 5,12-19<\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\">Mt 4,1-11<\/p>\n\n\n\n<p>A verdade \u00e9 que nossa vida \u00e9 absorvida por tantas preocupa\u00e7\u00f5es que n\u00e3o nos permitem de parar pelo menos um instante para entender de que lado est\u00e3o nos levando: se pelo menos existe um percurso a seguir que nos leve a felicidade, n\u00e3o aquela de um momento que depois deixa um sabor amargo; se a nossa vida ainda tem um sentido que nos guia, nos ilumina, nos orienta na hora de escolher o que podemos aceitar ou n\u00e3o, o que vale a pena viver ou n\u00e3o.<\/p>\n\n\n\n<p>Cristo tamb\u00e9m, ap\u00f3s trinta anos de uma vida harmoniosa com Maria e Jos\u00e9, seus pais, est\u00e1 muito preocupado, chegou a hora de realizar a sua miss\u00e3o, aquele anseio de justi\u00e7a e de amor, que Deus Pai colocou no seu cora\u00e7\u00e3o. A miss\u00e3o da vida se descobre nos desejos mais \u00edntimos que temos na nossa alma. Poucos dias atr\u00e1s um amigo me disse:\u201d Padre, n\u00e3o quero mais do que tenho. Se trabalhasse mais poderia duplicar, triplicar minha renda; mas n\u00e3o quero isso; quero mais tempo para amar minha fam\u00edlia; quero mais tempo para servir a Deus, conhecer sua Palavra, quero tempo para rezar, poder passear com meus caros\u201d.<\/p>\n\n\n\n<p>Qual \u00e9 seu desejo mais \u00edntimo?<\/p>\n\n\n\n<p>Se voc\u00ea n\u00e3o o descobre, sua vida ser\u00e1 uma corrida sem chegada, ser\u00e1 um sacrif\u00edcio sem valor ou pior ainda ser\u00e1 tomada pela superficialidade, pela vaidade, pela apar\u00eancia. Como uma pessoa cheia de produtos que aparece com um rosto brilhante, mas na solid\u00e3o do seu quarto n\u00e3o pode deixar de ver que, ca\u00eddos os produtos, seu rosto \u00e9 cheio de rugas. Assim pode ser a vida quando, na solid\u00e3o dos nossos pensamentos mais \u00edntimos, a aposta na apar\u00eancia nos deixa com um sabor amargo de quem n\u00e3o sabe permanecer na realidade deste mundo, mas vive como numa fic\u00e7\u00e3o teatral. Conhe\u00e7a seu desejo mais \u00edntimo e saber\u00e1 como e porque viver.<\/p>\n\n\n\n<p>As vezes vejo pessoas que se aproximam deste desejo: come\u00e7am a participar de algo novo, um trabalho volunt\u00e1rio, uma maneira de se doar, que est\u00e1 trazendo \u00e0 tona o desejo mais \u00edntimo daquela pessoa. Quando vejo pessoas que desistem disso, sofro profundamente, porque vejo claramente que aquela pessoa abandonou o caminho que a estava levando a se conhecer de verdade.<\/p>\n\n\n\n<p>Voltamos a Jesus. Jesus n\u00e3o queria perder o seu desejo de libertar seu povo: precisava anunciar o amor do Pai. Com 30 anos procura o deserto, n\u00e3o um lugar, mas um momento de silencio para verificar como teria realizado seu desejo \u00edntimo, sua voca\u00e7\u00e3o, sua miss\u00e3o.<\/p>\n\n\n\n<p>Neste tempo o advers\u00e1rio (satan\u00e1s) perturba Jesus.<\/p>\n\n\n\n<p><strong>A primeira tenta\u00e7\u00e3o \u00e9 de usar o poder divino: transformar pedras em p\u00e3o!<\/strong><\/p>\n\n\n\n<p>Quantos seguidores teria? Milh\u00f5es!<\/p>\n\n\n\n<p>Mas do que adiantaria dar o p\u00e3o se os homens n\u00e3o aprendessem a repartir. <em>\u201cN\u00e3o s\u00f3 de p\u00e3o vive o homem, mas de toda palavra que sai da boca de Deus&#8221;. (Mt 4,4)<\/em><\/p>\n\n\n\n<p>Jesus negando a proposta tentadora, reafirma que seu desejo \u00e9 ver um mundo mais fraterno. O caminho certo \u00e9 anunciar a Palavra para que os homens aprendam a conviver, aprendam a repartir o p\u00e3o.<\/p>\n\n\n\n<p>A m\u00e1gica do poder daria como fruto o p\u00e3o, mas n\u00e3o transformaria o cora\u00e7\u00e3o do homem. Jesus entende que seu desejo mais \u00edntimo \u00e9 transformar o cora\u00e7\u00e3o do homem, com o anuncio da Palavra de Deus.<\/p>\n\n\n\n<p><strong>A segunda tenta\u00e7\u00e3o: do aparecer, do f\u00e1cil, do extraordin\u00e1rio!<\/strong><\/p>\n\n\n\n<p>Quantos homens fazem de tudo para aparecer. Os produtores de TV, quiseram provar para o mundo, que na nossa cultura o importante \u00e9 a aparecer, ser famoso, ser reconhecido. Assim inventaram o BBB para mostrar que a TV n\u00e3o se alimenta convidando celebridades, mas ela mesma \u00e9 capaz de transformar qualquer pessoa em celebridade.<\/p>\n\n\n\n<p>Jesus, por\u00e9m, sabia muito bem que o caminho est\u00e1 na humildade, no crescer ficando na sombra, sem as luzes da fama e do sucesso. Acima de tudo n\u00e3o podemos \u201ctentar\u201d a Deus. Isto \u00e9, n\u00e3o se pode usar Deus para ser famosos. N\u00e3o se pode marcar milagre para Deus fazer. N\u00e3o podemos querer que Deus fa\u00e7a a nossa vontade, mas somos n\u00f3s que temos que fazer a Dele.<\/p>\n\n\n\n<p><strong>A \u00faltima tenta\u00e7\u00e3o resume todas: N\u00e3o se pode adorar um outro Deus.<\/strong><\/p>\n\n\n\n<p>N\u00e3o se pode cair na idolatria. N\u00e3o existe um diabo que possa nos doar o mundo. O tentador s\u00f3 poderia nos doar ilus\u00e3o, engana\u00e7\u00e3o, mentiras e com isso muito sofrimento. Algum domingo atr\u00e1s, Jesus advertia: <em>\u201cN\u00e3o podeis servir a Deus e ao dinheiro\u201d (Mt 6,24)<\/em>.<\/p>\n\n\n\n<p>A riqueza \u00e9 apenas uma das ilus\u00f5es deste mundo, talvez a mais tentadora e por isso a mais perigosa porque o mal nem sempre tem uma apar\u00eancia feia, mas muitas vezes nos engana porque se apresenta como atraente.<\/p>\n\n\n\n<p>Como Jesus, escolhemos Deus e seu projeto de vida e de amor. N\u00e3o vamos deixar que ningu\u00e9m tire o sonho que foi plantado por Deus no nosso cora\u00e7\u00e3o.<\/p>\n\n\n\n<p>Padre Graziano Cirina 15 de Mar\u00e7o de 2011<\/p>\n\n\n\n<p>Homilia publicada originalmente no <a href=\"https:\/\/sousagradosoufeliz.com\/a-coragem-de-olhar-dentro-de-nos.html\" target=\"_blank\" rel=\"noreferrer noopener\">site da Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus<\/a><\/p>\n\n\n\n<p><strong>Baixe o e-book com frases e reflex\u00f5es para a Quaresma do Padre Graziano clicando na imagem abaixo<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/padregraziano.com\/index.php\/2023\/02\/22\/e-book-padre-graziano\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" class=\"wp-image-778\" style=\"width: 500px;\" src=\"https:\/\/padregraziano.com\/wp-content\/uploads\/2023\/02\/Divulgacao-ebook-padre-Graziano_02.png\" alt=\"\" srcset=\"https:\/\/padregraziano.com\/wp-content\/uploads\/2023\/02\/Divulgacao-ebook-padre-Graziano_02.png 1080w, https:\/\/padregraziano.com\/wp-content\/uploads\/2023\/02\/Divulgacao-ebook-padre-Graziano_02-300x300.png 300w, https:\/\/padregraziano.com\/wp-content\/uploads\/2023\/02\/Divulgacao-ebook-padre-Graziano_02-1024x1024.png 1024w, https:\/\/padregraziano.com\/wp-content\/uploads\/2023\/02\/Divulgacao-ebook-padre-Graziano_02-150x150.png 150w, https:\/\/padregraziano.com\/wp-content\/uploads\/2023\/02\/Divulgacao-ebook-padre-Graziano_02-768x768.png 768w, https:\/\/padregraziano.com\/wp-content\/uploads\/2023\/02\/Divulgacao-ebook-padre-Graziano_02-600x600.png 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Homilia do 1\u00ba Domingo da Quaresma \u2013 Ano A (15\/03\/2011) Leituras: Gn 2,7-9.3,1-7 Sl 50(51),3-4.5-6a.12-13.14.17 (R. cf. 3a) ou ou mais breve 5,12.17-19 Rm 5,12-19 Mt 4,1-11 A verdade \u00e9 que nossa vida \u00e9 absorvida por tantas preocupa\u00e7\u00f5es que n\u00e3o nos permitem de parar pelo menos um instante para entender de que lado est\u00e3o nos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[20,22,38],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A coragem de olhar dentro de n\u00f3s - Memorial Padre Graziano Cirina<\/title>\n<meta name=\"description\" content=\"Homilia do padre Graziano para o 1\u00ba Domingo da Quaresma Ano A\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A coragem de olhar dentro de n\u00f3s - Memorial Padre Graziano Cirina\" \/>\n<meta property=\"og:description\" content=\"Homilia do padre Graziano para o 1\u00ba Domingo da Quaresma Ano A\" \/>\n<meta property=\"og:url\" content=\"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/\" \/>\n<meta property=\"og:site_name\" content=\"Memorial Padre Graziano Cirina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MemorialPadreGraziano\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-25T14:47:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-25T14:47:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/padregraziano.com\/wp-content\/uploads\/2023\/02\/Thumb-homilia-1_02.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Wender\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wender\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/\"},\"author\":{\"name\":\"Wender\",\"@id\":\"https:\/\/padregraziano.com\/#\/schema\/person\/13b38e004a1046fb575c26391d3b0af2\"},\"headline\":\"A coragem de olhar dentro de n\u00f3s\",\"datePublished\":\"2023-02-25T14:47:17+00:00\",\"dateModified\":\"2023-02-25T14:47:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/\"},\"wordCount\":926,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/padregraziano.com\/#organization\"},\"keywords\":[\"Ano A\",\"Homilias\",\"Quaresma\"],\"articleSection\":[\"Homilias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/\",\"url\":\"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/\",\"name\":\"A coragem de olhar dentro de n\u00f3s - Memorial Padre Graziano Cirina\",\"isPartOf\":{\"@id\":\"https:\/\/padregraziano.com\/#website\"},\"datePublished\":\"2023-02-25T14:47:17+00:00\",\"dateModified\":\"2023-02-25T14:47:19+00:00\",\"description\":\"Homilia do padre Graziano para o 1\u00ba Domingo da Quaresma Ano A\",\"breadcrumb\":{\"@id\":\"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/padregraziano.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A coragem de olhar dentro de n\u00f3s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/padregraziano.com\/#website\",\"url\":\"https:\/\/padregraziano.com\/\",\"name\":\"Memorial Padre Graziano Cirina\",\"description\":\"Site dedicado a manter viva a mem\u00f3ria do padre Graziano Cirina\",\"publisher\":{\"@id\":\"https:\/\/padregraziano.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/padregraziano.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/padregraziano.com\/#organization\",\"name\":\"Memorial Padre Graziano Cirina\",\"url\":\"https:\/\/padregraziano.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/padregraziano.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/padregraziano.com\/wp-content\/uploads\/2022\/06\/Sem-titulo-1.png\",\"contentUrl\":\"https:\/\/padregraziano.com\/wp-content\/uploads\/2022\/06\/Sem-titulo-1.png\",\"width\":1080,\"height\":361,\"caption\":\"Memorial Padre Graziano Cirina\"},\"image\":{\"@id\":\"https:\/\/padregraziano.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/memorialpadregraziano\/\",\"https:\/\/www.youtube.com\/channel\/UC-8LlZNOI_0L6AEaMkpTY5A\",\"https:\/\/www.facebook.com\/MemorialPadreGraziano\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/padregraziano.com\/#\/schema\/person\/13b38e004a1046fb575c26391d3b0af2\",\"name\":\"Wender\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/padregraziano.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/caf2b99e3c54a90c84f77b267dc0025e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/caf2b99e3c54a90c84f77b267dc0025e?s=96&d=mm&r=g\",\"caption\":\"Wender\"},\"sameAs\":[\"http:\/\/padregraziano.com\"],\"url\":\"https:\/\/padregraziano.com\/index.php\/author\/wender\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A coragem de olhar dentro de n\u00f3s - Memorial Padre Graziano Cirina","description":"Homilia do padre Graziano para o 1\u00ba Domingo da Quaresma Ano A","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/","og_locale":"pt_BR","og_type":"article","og_title":"A coragem de olhar dentro de n\u00f3s - Memorial Padre Graziano Cirina","og_description":"Homilia do padre Graziano para o 1\u00ba Domingo da Quaresma Ano A","og_url":"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/","og_site_name":"Memorial Padre Graziano Cirina","article_publisher":"https:\/\/www.facebook.com\/MemorialPadreGraziano","article_published_time":"2023-02-25T14:47:17+00:00","article_modified_time":"2023-02-25T14:47:19+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/padregraziano.com\/wp-content\/uploads\/2023\/02\/Thumb-homilia-1_02.png","type":"image\/png"}],"author":"Wender","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Wender","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/#article","isPartOf":{"@id":"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/"},"author":{"name":"Wender","@id":"https:\/\/padregraziano.com\/#\/schema\/person\/13b38e004a1046fb575c26391d3b0af2"},"headline":"A coragem de olhar dentro de n\u00f3s","datePublished":"2023-02-25T14:47:17+00:00","dateModified":"2023-02-25T14:47:19+00:00","mainEntityOfPage":{"@id":"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/"},"wordCount":926,"commentCount":0,"publisher":{"@id":"https:\/\/padregraziano.com\/#organization"},"keywords":["Ano A","Homilias","Quaresma"],"articleSection":["Homilias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/","url":"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/","name":"A coragem de olhar dentro de n\u00f3s - Memorial Padre Graziano Cirina","isPartOf":{"@id":"https:\/\/padregraziano.com\/#website"},"datePublished":"2023-02-25T14:47:17+00:00","dateModified":"2023-02-25T14:47:19+00:00","description":"Homilia do padre Graziano para o 1\u00ba Domingo da Quaresma Ano A","breadcrumb":{"@id":"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/padregraziano.com\/index.php\/2023\/02\/25\/1o-domingo-da-quaresma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/padregraziano.com\/"},{"@type":"ListItem","position":2,"name":"A coragem de olhar dentro de n\u00f3s"}]},{"@type":"WebSite","@id":"https:\/\/padregraziano.com\/#website","url":"https:\/\/padregraziano.com\/","name":"Memorial Padre Graziano Cirina","description":"Site dedicado a manter viva a mem\u00f3ria do padre Graziano Cirina","publisher":{"@id":"https:\/\/padregraziano.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/padregraziano.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/padregraziano.com\/#organization","name":"Memorial Padre Graziano Cirina","url":"https:\/\/padregraziano.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/padregraziano.com\/#\/schema\/logo\/image\/","url":"https:\/\/padregraziano.com\/wp-content\/uploads\/2022\/06\/Sem-titulo-1.png","contentUrl":"https:\/\/padregraziano.com\/wp-content\/uploads\/2022\/06\/Sem-titulo-1.png","width":1080,"height":361,"caption":"Memorial Padre Graziano Cirina"},"image":{"@id":"https:\/\/padregraziano.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/memorialpadregraziano\/","https:\/\/www.youtube.com\/channel\/UC-8LlZNOI_0L6AEaMkpTY5A","https:\/\/www.facebook.com\/MemorialPadreGraziano"]},{"@type":"Person","@id":"https:\/\/padregraziano.com\/#\/schema\/person\/13b38e004a1046fb575c26391d3b0af2","name":"Wender","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/padregraziano.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/caf2b99e3c54a90c84f77b267dc0025e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/caf2b99e3c54a90c84f77b267dc0025e?s=96&d=mm&r=g","caption":"Wender"},"sameAs":["http:\/\/padregraziano.com"],"url":"https:\/\/padregraziano.com\/index.php\/author\/wender\/"}]}},"_links":{"self":[{"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/posts\/787"}],"collection":[{"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/comments?post=787"}],"version-history":[{"count":1,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/posts\/787\/revisions"}],"predecessor-version":[{"id":789,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/posts\/787\/revisions\/789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/media\/788"}],"wp:attachment":[{"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/media?parent=787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/categories?post=787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/tags?post=787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}