{"id":713,"date":"2022-12-30T13:10:57","date_gmt":"2022-12-30T16:10:57","guid":{"rendered":"https:\/\/padregraziano.com\/?p=713"},"modified":"2022-12-30T13:10:59","modified_gmt":"2022-12-30T16:10:59","slug":"sagrada-familia","status":"publish","type":"post","link":"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/","title":{"rendered":"<strong>A Sagrada Fam\u00edlia \u2013 O amor que estrutura o ser<\/strong>"},"content":{"rendered":"\n<p><strong>Homilia da solenidade da Sagrada Fam\u00edlia (02\/01\/2018)<\/strong><\/p>\n\n\n\n<p>Poderia falar da fam\u00edlia ideal, quase com um tom po\u00e9tico. Todavia sinto a necessidade de falar sem poesias, mas com realismo. Vou ser realista ao falar de fam\u00edlia. A Sagrada Fam\u00edlia n\u00e3o \u00e9 o modelo das fam\u00edlias na sua forma, mas \u00e9 modelo na intensidade do seu amor, at\u00e9 onde o conhecemos, pois, a fam\u00edlia de Nazar\u00e9 \u00e9 muito diferente do normal. Uma m\u00e3e, virgem escolhida para ser a m\u00e3e do Salvador; Jos\u00e9, esposo que depois da inf\u00e2ncia de Jesus simplesmente some e dele nada mais sabemos, e Jesus, um filho que se nos base\u00e1ssemos nos fatos hist\u00f3ricos permanece com a fam\u00edlia mais de 80% de sua vida, para sair j\u00e1 adulto os \u00faltimos tr\u00eas anos de sua vida em uma miss\u00e3o que o leva a morte.<\/p>\n\n\n\n<p>Pouco sabemos dos 30 anos de Nazar\u00e9. Podemos imaginar, por\u00e9m muito mais: dever\u00edamos aprender com todo o ensinamento de Jesus que mostra os pilares do amor maduro. Quando falamos de fam\u00edlia falamos do amor maduro.<\/p>\n\n\n\n<p>O evangelho nos fala de amor maduro, n\u00e3o do amor que suga, que domina, que explora. O evangelho nos fala do amor como doa\u00e7\u00e3o mutua, generosidade, amor gratuito, perd\u00e3o, acolhida, compreens\u00e3o, cura, conforto e apoio, que s\u00e3o os pilares do amor que vivemos desde o nosso nascimento.<\/p>\n\n\n\n<p>\u00c9 uma grande contradi\u00e7\u00e3o vir ao mundo de gra\u00e7a e por um amor generoso para depois desenvolver uma vida baseada em interesses pessoais. O que a fam\u00edlia nos ensina \u00e9 que amor \u00e9 responsabilidade, \u00e9 respeito, \u00e9 cuidado para todos, \u00e9 acolhida, \u00e9 compromisso com a necessidade do outro. Fam\u00edlia \u00e9 tudo ao contr\u00e1rio do que a nossa cultura de exagerado individualismo est\u00e1 causando: pessoas dentro de casa que vivem como ilhas, ou como um lugar de passagem aonde uma pessoa vai quando lhe \u00e9 conveniente, ou quando quer reclamar seus direitos, sem nunca se preocupar com seus deveres.<\/p>\n\n\n\n<p>Diz-se e se fala muito, com verdade, que vivemos uma grande crise das institui\u00e7\u00f5es e a fam\u00edlia \u00e9 uma das mais atingidas, mas, na verdade, a grande crise est\u00e1 nas pessoas. As pessoas que desaprenderam a amar, a se doar. Em crise est\u00e1 a educa\u00e7\u00e3o que transmite o pior da cultura que vivemos, que em lugar de amar as crian\u00e7as de verdade, dando para elas instrumentos para construir suas vidas, fica apenas paparicando-as, sem coragem de impor limites, encaminhando-as para uma fragilidade estrutural, que faz delas pessoas sem for\u00e7a para viver, sem for\u00e7as para aceitar derrotas.<\/p>\n\n\n\n<p>A educa\u00e7\u00e3o sem a imposi\u00e7\u00e3o de limites \u00e9 um falso amor que machuca as crian\u00e7as para sempre. Sorte para alguns, que a vida imp\u00f5e seus limites e, mesmo na marra, jovens se estruturam aprendendo no dia a dia aquilo que em casa n\u00e3o aprenderam.<\/p>\n\n\n\n<p>N\u00e3o precisamos de pr\u00edncipes e rainhas, precisamos de gente que sabe construir suas vidas no amor e na liberdade. N\u00e3o precisamos de contos de fadas, precisamos de gente que sabe correr atr\u00e1s de sonhos verdadeiros, sonhos comuns que s\u00e3o a constru\u00e7\u00e3o da realidade. A fam\u00edlia no projeto de Deus \u00e9 o lugar onde as pessoas aprendem a amar e ser amadas. A fam\u00edlia deve ensinar a preocupar-se com o SER e n\u00e3o com o TER.<\/p>\n\n\n\n<p>Padre Graziano<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Homilia escrita em 02\/01\/2018 e postada originalmente no <a href=\"https:\/\/sousagradosoufeliz.com\/a-sagrada-familia-o-amor-que-estrutura-o-ser-homilia-da-festa-da-sagrada-familia.html\" target=\"_blank\" rel=\"noreferrer noopener\">site da Par\u00f3quia Sagrado Cora\u00e7\u00e3o de Jesus<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Homilia da solenidade da Sagrada Fam\u00edlia (02\/01\/2018) Poderia falar da fam\u00edlia ideal, quase com um tom po\u00e9tico. Todavia sinto a necessidade de falar sem poesias, mas com realismo. Vou ser realista ao falar de fam\u00edlia. A Sagrada Fam\u00edlia n\u00e3o \u00e9 o modelo das fam\u00edlias na sua forma, mas \u00e9 modelo na intensidade do seu amor, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[26,27,22,25],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Sagrada Fam\u00edlia \u2013 O amor que estrutura o ser - Memorial Padre Graziano Cirina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Sagrada Fam\u00edlia \u2013 O amor que estrutura o ser - Memorial Padre Graziano Cirina\" \/>\n<meta property=\"og:description\" content=\"Homilia da solenidade da Sagrada Fam\u00edlia (02\/01\/2018) Poderia falar da fam\u00edlia ideal, quase com um tom po\u00e9tico. Todavia sinto a necessidade de falar sem poesias, mas com realismo. Vou ser realista ao falar de fam\u00edlia. A Sagrada Fam\u00edlia n\u00e3o \u00e9 o modelo das fam\u00edlias na sua forma, mas \u00e9 modelo na intensidade do seu amor, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/\" \/>\n<meta property=\"og:site_name\" content=\"Memorial Padre Graziano Cirina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MemorialPadreGraziano\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-30T16:10:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-30T16:10:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/padregraziano.com\/wp-content\/uploads\/2022\/12\/Sagrada-Familia_02.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Wender\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wender\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/\"},\"author\":{\"name\":\"Wender\",\"@id\":\"https:\/\/padregraziano.com\/#\/schema\/person\/13b38e004a1046fb575c26391d3b0af2\"},\"headline\":\"A Sagrada Fam\u00edlia \u2013 O amor que estrutura o ser\",\"datePublished\":\"2022-12-30T16:10:57+00:00\",\"dateModified\":\"2022-12-30T16:10:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/\"},\"wordCount\":589,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/padregraziano.com\/#organization\"},\"keywords\":[\"Ano B\",\"Fam\u00edlia\",\"Homilias\",\"Natal\"],\"articleSection\":[\"Homilias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/\",\"url\":\"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/\",\"name\":\"A Sagrada Fam\u00edlia \u2013 O amor que estrutura o ser - Memorial Padre Graziano Cirina\",\"isPartOf\":{\"@id\":\"https:\/\/padregraziano.com\/#website\"},\"datePublished\":\"2022-12-30T16:10:57+00:00\",\"dateModified\":\"2022-12-30T16:10:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/padregraziano.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Sagrada Fam\u00edlia \u2013 O amor que estrutura o ser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/padregraziano.com\/#website\",\"url\":\"https:\/\/padregraziano.com\/\",\"name\":\"Memorial Padre Graziano Cirina\",\"description\":\"Site dedicado a manter viva a mem\u00f3ria do padre Graziano Cirina\",\"publisher\":{\"@id\":\"https:\/\/padregraziano.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/padregraziano.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/padregraziano.com\/#organization\",\"name\":\"Memorial Padre Graziano Cirina\",\"url\":\"https:\/\/padregraziano.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/padregraziano.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/padregraziano.com\/wp-content\/uploads\/2022\/06\/Sem-titulo-1.png\",\"contentUrl\":\"https:\/\/padregraziano.com\/wp-content\/uploads\/2022\/06\/Sem-titulo-1.png\",\"width\":1080,\"height\":361,\"caption\":\"Memorial Padre Graziano Cirina\"},\"image\":{\"@id\":\"https:\/\/padregraziano.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/memorialpadregraziano\/\",\"https:\/\/www.youtube.com\/channel\/UC-8LlZNOI_0L6AEaMkpTY5A\",\"https:\/\/www.facebook.com\/MemorialPadreGraziano\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/padregraziano.com\/#\/schema\/person\/13b38e004a1046fb575c26391d3b0af2\",\"name\":\"Wender\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/padregraziano.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/caf2b99e3c54a90c84f77b267dc0025e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/caf2b99e3c54a90c84f77b267dc0025e?s=96&d=mm&r=g\",\"caption\":\"Wender\"},\"sameAs\":[\"http:\/\/padregraziano.com\"],\"url\":\"https:\/\/padregraziano.com\/index.php\/author\/wender\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Sagrada Fam\u00edlia \u2013 O amor que estrutura o ser - Memorial Padre Graziano Cirina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/","og_locale":"pt_BR","og_type":"article","og_title":"A Sagrada Fam\u00edlia \u2013 O amor que estrutura o ser - Memorial Padre Graziano Cirina","og_description":"Homilia da solenidade da Sagrada Fam\u00edlia (02\/01\/2018) Poderia falar da fam\u00edlia ideal, quase com um tom po\u00e9tico. Todavia sinto a necessidade de falar sem poesias, mas com realismo. Vou ser realista ao falar de fam\u00edlia. A Sagrada Fam\u00edlia n\u00e3o \u00e9 o modelo das fam\u00edlias na sua forma, mas \u00e9 modelo na intensidade do seu amor, [&hellip;]","og_url":"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/","og_site_name":"Memorial Padre Graziano Cirina","article_publisher":"https:\/\/www.facebook.com\/MemorialPadreGraziano","article_published_time":"2022-12-30T16:10:57+00:00","article_modified_time":"2022-12-30T16:10:59+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/padregraziano.com\/wp-content\/uploads\/2022\/12\/Sagrada-Familia_02.png","type":"image\/png"}],"author":"Wender","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Wender","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/#article","isPartOf":{"@id":"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/"},"author":{"name":"Wender","@id":"https:\/\/padregraziano.com\/#\/schema\/person\/13b38e004a1046fb575c26391d3b0af2"},"headline":"A Sagrada Fam\u00edlia \u2013 O amor que estrutura o ser","datePublished":"2022-12-30T16:10:57+00:00","dateModified":"2022-12-30T16:10:59+00:00","mainEntityOfPage":{"@id":"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/"},"wordCount":589,"commentCount":0,"publisher":{"@id":"https:\/\/padregraziano.com\/#organization"},"keywords":["Ano B","Fam\u00edlia","Homilias","Natal"],"articleSection":["Homilias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/","url":"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/","name":"A Sagrada Fam\u00edlia \u2013 O amor que estrutura o ser - Memorial Padre Graziano Cirina","isPartOf":{"@id":"https:\/\/padregraziano.com\/#website"},"datePublished":"2022-12-30T16:10:57+00:00","dateModified":"2022-12-30T16:10:59+00:00","breadcrumb":{"@id":"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/padregraziano.com\/index.php\/2022\/12\/30\/sagrada-familia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/padregraziano.com\/"},{"@type":"ListItem","position":2,"name":"A Sagrada Fam\u00edlia \u2013 O amor que estrutura o ser"}]},{"@type":"WebSite","@id":"https:\/\/padregraziano.com\/#website","url":"https:\/\/padregraziano.com\/","name":"Memorial Padre Graziano Cirina","description":"Site dedicado a manter viva a mem\u00f3ria do padre Graziano Cirina","publisher":{"@id":"https:\/\/padregraziano.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/padregraziano.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/padregraziano.com\/#organization","name":"Memorial Padre Graziano Cirina","url":"https:\/\/padregraziano.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/padregraziano.com\/#\/schema\/logo\/image\/","url":"https:\/\/padregraziano.com\/wp-content\/uploads\/2022\/06\/Sem-titulo-1.png","contentUrl":"https:\/\/padregraziano.com\/wp-content\/uploads\/2022\/06\/Sem-titulo-1.png","width":1080,"height":361,"caption":"Memorial Padre Graziano Cirina"},"image":{"@id":"https:\/\/padregraziano.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/memorialpadregraziano\/","https:\/\/www.youtube.com\/channel\/UC-8LlZNOI_0L6AEaMkpTY5A","https:\/\/www.facebook.com\/MemorialPadreGraziano"]},{"@type":"Person","@id":"https:\/\/padregraziano.com\/#\/schema\/person\/13b38e004a1046fb575c26391d3b0af2","name":"Wender","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/padregraziano.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/caf2b99e3c54a90c84f77b267dc0025e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/caf2b99e3c54a90c84f77b267dc0025e?s=96&d=mm&r=g","caption":"Wender"},"sameAs":["http:\/\/padregraziano.com"],"url":"https:\/\/padregraziano.com\/index.php\/author\/wender\/"}]}},"_links":{"self":[{"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/posts\/713"}],"collection":[{"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/comments?post=713"}],"version-history":[{"count":1,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/posts\/713\/revisions"}],"predecessor-version":[{"id":715,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/posts\/713\/revisions\/715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/media\/714"}],"wp:attachment":[{"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/media?parent=713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/categories?post=713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/padregraziano.com\/index.php\/wp-json\/wp\/v2\/tags?post=713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}